{"id":1052,"date":"2018-07-27T09:45:58","date_gmt":"2018-07-27T09:45:58","guid":{"rendered":"http:\/\/www.seha.com.tr\/about-us\/work-experience-references\/"},"modified":"2023-09-18T14:27:39","modified_gmt":"2023-09-18T14:27:39","slug":"work-experience-references","status":"publish","type":"page","link":"https:\/\/www.seha.com.tr\/en\/about-us\/work-experience-references\/","title":{"rendered":"Work Experience References"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1052\" class=\"elementor elementor-1052 elementor-256\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5425fc38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5425fc38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7b21d196\" data-id=\"7b21d196\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-680059e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"680059e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w42.png\" class=\"attachment-full size-full wp-image-1141\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Central Finance &amp; Contracts Unit<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-719e912 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"719e912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w45.png\" class=\"attachment-full size-full wp-image-1143\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">World Bank<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77f0084 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"77f0084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w43.png\" class=\"attachment-full size-full wp-image-1081\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">United Nations<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ae302e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"2ae302e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w31.png\" class=\"attachment-full size-full wp-image-1073\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ford Motor Company<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f99d9d7 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"f99d9d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w37.png\" class=\"attachment-full size-full wp-image-1077\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">FIAT TOFA\u015e<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83c2408 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"83c2408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w36.png\" class=\"attachment-full size-full wp-image-1137\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TAN OTO<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a077946 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"a077946\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w04.png\" class=\"attachment-full size-full wp-image-1055\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ministry of National Education<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d1fb3 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"d8d1fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w07.png\" class=\"attachment-full size-full wp-image-1057\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Republic of Turkey Ministry of Health<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2781f3a elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"2781f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w13.png\" class=\"attachment-full size-full wp-image-1061\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Special Provincial Administrations<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e017d3b elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e017d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w16.png\" class=\"attachment-full size-full wp-image-1063\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Social Security Institution<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fabc05 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"4fabc05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w19.png\" class=\"attachment-full size-full wp-image-1065\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Social Security Institution<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3295d6b elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"3295d6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w22.png\" class=\"attachment-full size-full wp-image-1067\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Cement Manufacturers Association of Turkey<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a66300 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"7a66300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w28.png\" class=\"attachment-full size-full wp-image-1071\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Mechanical and Chemical Industry Corporation<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2368347 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"2368347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w25.png\" class=\"attachment-full size-full wp-image-1069\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Cyprus Ministry of Forestry<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-890cb19\" data-id=\"890cb19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9daf99 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e9daf99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2019\/05\/w-eu.png\" class=\"attachment-full size-full wp-image-2085\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Delegation of the European Union to Turkey<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a3a846 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"6a3a846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w41.png\" class=\"attachment-full size-full wp-image-1111\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">EULEX Kosovo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec9dda3 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"ec9dda3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w46.png\" class=\"attachment-full size-full wp-image-1083\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">United Nations Development Programme\u2019s <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b416cb2 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"b416cb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w39.png\" class=\"attachment-full size-full wp-image-1139\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">RENAULT MAIS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-898cfa6 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"898cfa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w32.png\" class=\"attachment-full size-full wp-image-1105\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">OTOKO\u00c7<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83fc044 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"83fc044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w38.png\" class=\"attachment-full size-full wp-image-1109\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TEMSA<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ade2c52 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"ade2c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w05.png\" class=\"attachment-full size-full wp-image-1087\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ministry of Science, Industry and Technology<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58acf99 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"58acf99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w08.png\" class=\"attachment-full size-full wp-image-1089\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Environment and Urban Ministry<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-007a662 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"007a662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w11.png\" class=\"attachment-full size-full wp-image-1091\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ministry of Transport, Maritime Affairs and Communication<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e067eb8 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e067eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w14-1.png\" class=\"attachment-full size-full wp-image-1093\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Undersecretariat of Customs<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b9736e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"6b9736e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w17.png\" class=\"attachment-full size-full wp-image-1095\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">General Directorate of State Hydraulic Works<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-378213a elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"378213a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w20.png\" class=\"attachment-full size-full wp-image-1097\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">General Directorate of State Hydraulic Works<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c4e71 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"59c4e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w23.png\" class=\"attachment-full size-full wp-image-1099\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">General Directorate of State Hydraulic Works<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f43d9 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"66f43d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w26.png\" class=\"attachment-full size-full wp-image-1101\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Small and Medium Enterprises Development Organization<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04288f1 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"04288f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w30.png\" class=\"attachment-full size-full wp-image-1133\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">NUROL<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c933e5c\" data-id=\"c933e5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21b7236 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"21b7236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w40.png\" class=\"attachment-full size-full wp-image-1079\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">EUROPEAID (Cyprus), (Lebanon), (Belarus), (Croatia)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5466808 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"5466808\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w44.png\" class=\"attachment-full size-full wp-image-1113\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">FAO<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a52300a elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"a52300a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2019\/05\/w-unhcr.png\" class=\"attachment-full size-full wp-image-2088\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">The UN Refugee Agency<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aaadae7 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"aaadae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w35.png\" class=\"attachment-full size-full wp-image-1107\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TOYOTA TOYAN<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e77dd26 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e77dd26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w34.png\" class=\"attachment-full size-full wp-image-1075\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">DO\u011eU\u015e AUTOMOTIVE<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e2f222 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"0e2f222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w29.png\" class=\"attachment-full size-full wp-image-1103\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">ASELSAN<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8adb76a elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"8adb76a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w06.png\" class=\"attachment-full size-full wp-image-1117\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Republic of Turkey Ministry of Food, Agriculture and Livestock<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0dd30a elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e0dd30a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w09.png\" class=\"attachment-full size-full wp-image-1119\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">The Ministry of Labor and Social Security<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b229a1c elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"b229a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w12.png\" class=\"attachment-full size-full wp-image-1121\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">The Ministry of Labor and Social Security<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6965cc elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e6965cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w15.png\" class=\"attachment-full size-full wp-image-1123\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Republic of Turkey Ministry of Interior Directorate General of Migration Management<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81bde52 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"81bde52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w18.png\" class=\"attachment-full size-full wp-image-1125\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Electrical Power Resources Survey<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e8b27 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"d6e8b27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w21.png\" class=\"attachment-full size-full wp-image-1127\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">The Scientific and Technologic Research Council of Turkey<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c52e37 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"8c52e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w24.png\" class=\"attachment-full size-full wp-image-1129\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">KU\u015e-ATAK Association of Municipalities<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa8fe9f elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"aa8fe9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"82\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w27.png\" class=\"attachment-full size-full wp-image-1131\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">The General Secretariat of Istanbul Textile &amp; Apparel Exporters Associations<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e5dc3 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"43e5dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"81\" src=\"https:\/\/www.seha.com.tr\/wp-content\/uploads\/2018\/05\/w33.png\" class=\"attachment-full size-full wp-image-1135\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">KAYATUR<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ecaf74b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ecaf74b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4deeb0e8\" data-id=\"4deeb0e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-443956c0 elementor-widget elementor-widget-text-editor\" data-id=\"443956c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">Please contact us for more information about our work experiences<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Central Finance &#038; Contracts Unit World Bank United Nations Ford Motor Company FIAT TOFA\u015e TAN OTO Ministry of National Education Republic of Turkey Ministry of Health Special Provincial Administrations Social Security Institution Social Security Institution Cement Manufacturers Association of Turkey Mechanical and Chemical Industry Corporation Cyprus Ministry of Forestry Delegation of the European Union to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1002,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1052","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/pages\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/comments?post=1052"}],"version-history":[{"count":16,"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/pages\/1052\/revisions"}],"predecessor-version":[{"id":2627,"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/pages\/1052\/revisions\/2627"}],"up":[{"embeddable":true,"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/pages\/1002"}],"wp:attachment":[{"href":"https:\/\/www.seha.com.tr\/en\/wp-json\/wp\/v2\/media?parent=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}